{"id":9828,"date":"2019-07-25T12:27:03","date_gmt":"2019-07-25T12:27:03","guid":{"rendered":"https:\/\/kb.mailfence.com\/kb\/como-exporto-datos-de-una-cuenta-mailfence\/"},"modified":"2025-12-19T07:28:36","modified_gmt":"2025-12-19T07:28:36","slug":"como-exporto-datos-de-una-cuenta-mailfence","status":"publish","type":"ht_kb","link":"https:\/\/kb.mailfence.com\/es\/kb\/como-exporto-datos-de-una-cuenta-mailfence\/","title":{"rendered":"\u00bfC\u00f3mo exporto datos de una cuenta Mailfence?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Puedes exportar datos desde la interfaz web de Mailfence de las dos formas siguientes:<\/p>\n\n\n\n<div class=\"wp-block-ht-block-toc  is-style-outline htoc htoc--position-wide toc-list-style-plain\" data-htoc-state=\"expanded\" data-htoc-scrollspy=\"false\" data-htoc-auto-collapse=\"true\" data-htoc-mapping-headers=\"[false,true,true,true,true,true]\"><span class=\"htoc__title\"><span class=\"ht_toc_title\">\u00cdndice<\/span><span class=\"htoc__toggle\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\"><g fill=\"#444\"><path d=\"M15 7H1c-.6 0-1 .4-1 1s.4 1 1 1h14c.6 0 1-.4 1-1s-.4-1-1-1z\"><\/path><path d=\"M15 1H1c-.6 0-1 .4-1 1s.4 1 1 1h14c.6 0 1-.4 1-1s-.4-1-1-1zM15 13H1c-.6 0-1 .4-1 1s.4 1 1 1h14c.6 0 1-.4 1-1s-.4-1-1-1z\"><\/path><\/g><\/svg><\/span><\/span><div class=\"htoc__itemswrap\"><ul class=\"ht_toc_list\"><li class=\"\"><a href=\"#h-crea-una-copia-de-seguridad\">Crea una copia de seguridad:<\/a><\/li><li class=\"\"><a href=\"#htoc-export-selected-items\">Exportar elementos seleccionados<\/a><ul class=\"ht_toc_child_list\"><li class=\"\"><a href=\"#htoc-for-exporting-a-specific-email\">Para exportar un correo electr\u00f3nico concreto:<\/a><\/li><li class=\"\"><a href=\"#htoc-for-exporting-a-specific-document\">Para exportar un documento concreto:<\/a><\/li><li class=\"\"><a href=\"#htoc-for-exporting-a-specific-calendar-event\">Para exportar un evento concreto del calendario:<\/a><\/li><li class=\"\"><a href=\"#htoc-for-exporting-a-specific-contact\">Para exportar un contacto concreto:<\/a><\/li><li class=\"\"><a href=\"#htoc-for-exporting-your-openpgp-keypair-s-other-public-keys\">Para exportar tu(s) par(es) de claves OpenPGP\/otras claves p\u00fablicas:<\/a><\/li><\/ul><\/li><\/ul><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-crea-una-copia-de-seguridad\">Crea una copia de seguridad:<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"> <strong>1. Ajustes<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"199\" height=\"310\" src=\"https:\/\/kb.mailfence.com\/wp-content\/uploads\/2019\/12\/setting-8.png\" alt=\"exportar datos desde mailfence: paso 1\" class=\"wp-image-839\" srcset=\"https:\/\/kb.mailfence.com\/wp-content\/uploads\/2019\/12\/setting-8.png 199w, https:\/\/kb.mailfence.com\/wp-content\/uploads\/2019\/12\/setting-8-193x300.png 193w, https:\/\/kb.mailfence.com\/wp-content\/uploads\/2019\/12\/setting-8-32x50.png 32w, https:\/\/kb.mailfence.com\/wp-content\/uploads\/2019\/12\/setting-8-39x60.png 39w, https:\/\/kb.mailfence.com\/wp-content\/uploads\/2019\/12\/setting-8-64x100.png 64w\" sizes=\"auto, (max-width: 199px) 100vw, 199px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>2. Cuenta -&gt; Copia de seguridad:<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"178\" height=\"257\" src=\"https:\/\/kb.mailfence.com\/wp-content\/uploads\/2019\/12\/back-up.png\" alt=\"exportar datos desde mailfence: paso 2\" class=\"wp-image-840\" srcset=\"https:\/\/kb.mailfence.com\/wp-content\/uploads\/2019\/12\/back-up.png 178w, https:\/\/kb.mailfence.com\/wp-content\/uploads\/2019\/12\/back-up-35x50.png 35w, https:\/\/kb.mailfence.com\/wp-content\/uploads\/2019\/12\/back-up-42x60.png 42w, https:\/\/kb.mailfence.com\/wp-content\/uploads\/2019\/12\/back-up-69x100.png 69w\" sizes=\"auto, (max-width: 178px) 100vw, 178px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>3. Pulsa Exportar despu\u00e9s de elegir el elemento que quieras<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"281\" height=\"191\" src=\"https:\/\/kb.mailfence.com\/wp-content\/uploads\/2019\/12\/select.png\" alt=\"exportar datos desde mailfence: paso 3\" class=\"wp-image-841\" srcset=\"https:\/\/kb.mailfence.com\/wp-content\/uploads\/2019\/12\/select.png 281w, https:\/\/kb.mailfence.com\/wp-content\/uploads\/2019\/12\/select-50x34.png 50w, https:\/\/kb.mailfence.com\/wp-content\/uploads\/2019\/12\/select-60x41.png 60w, https:\/\/kb.mailfence.com\/wp-content\/uploads\/2019\/12\/select-100x68.png 100w\" sizes=\"auto, (max-width: 281px) 100vw, 281px\" \/><figcaption class=\"wp-element-caption\">Ten en cuenta que la opci\u00f3n de copia de seguridad de los correos electr\u00f3nicos no est\u00e1 disponible en la suscripci\u00f3n gratuita<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-ht-blocks-messages wp-block-hb-message wp-block-hb-message--withicon is-style-info\">La restricci\u00f3n en el tama\u00f1o de los archivos de copia de seguridad se aplica por razones de rendimiento, por ejemplo, para documentos: hasta 250 MB de datos. Si necesitas hacer una copia de seguridad de un gran volumen de datos, utiliza clientes externos, por ejemplo, cliente CardDAV\/EAS para contactos, cliente CalDAV\/EAS para eventos de calendario, cliente WebDAV para documentos y cliente IMAP para correos electr\u00f3nicos. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"htoc-export-selected-items\">Exportar elementos seleccionados<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"htoc-for-exporting-a-specific-email\">Para exportar un correo electr\u00f3nico concreto:<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li id=\"htoc-haz-clic-con-el-bot-n-derecho-del-rat-n-sobre-el-mensaje-en-el-panel-de-la-lista-de-mensajes-archivar-descargar-ten-en-cuenta-que-esta-opci-n-no-est-disponible-en-la-suscripci-n-gratuita\"><strong>Haz clic con el bot\u00f3n derecho del rat\u00f3n<\/strong> sobre el <strong>mensaje<\/strong> en el <strong>panel de la lista de mensajes<\/strong> -> <strong>Archivar<\/strong> -> <strong>Descargar<\/strong>. Al utilizar la opci\u00f3n de archivar\/descargar, la exportaci\u00f3n se realizar\u00e1 en un archivo .eml.<\/li>\n\n\n\n<li id=\"htoc-si-prefiere-otro-formato-puede-utilizar-un-programa-imap\">Si prefiere otro formato, puede utilizar un programa IMAP.<\/li>\n\n\n\n<li id=\"htoc-haz-clic-con-el-bot-n-derecho-del-rat-n-sobre-el-mensaje-en-el-panel-de-la-lista-de-mensajes-archivar-descargar-ten-en-cuenta-que-esta-opci-n-no-est-disponible-en-la-suscripci-n-gratuita11\">Ten en cuenta que esta opci\u00f3n no est\u00e1 disponible en la suscripci\u00f3n gratuita.<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/kb.mailfence.com\/wp-content\/uploads\/2022\/03\/email-export.gif\" alt=\"exportar datos de Mailfence\" class=\"wp-image-2805\"\/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\" id=\"htoc-for-exporting-a-specific-document\">Para exportar un documento concreto:<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li id=\"htoc-haz-clic-con-el-bot-n-derecho-en-el-documento-descargar\"><strong>Haz clic con el bot\u00f3n derecho<\/strong> en el documento -> <strong>Descargar<\/strong>.<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/kb.mailfence.com\/wp-content\/uploads\/2022\/03\/doc-export.gif\" alt=\"exportar datos de Mailfence\" class=\"wp-image-2804\"\/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\" id=\"htoc-for-exporting-a-specific-calendar-event\">Para exportar un evento concreto del calendario:<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li id=\"htoc-haz-clic-con-el-bot-n-derecho-en-el-evento-del-calendario-exportar\"><strong>Haz clic con el bot\u00f3n derecho<\/strong> en el evento del calendario -> <strong>Exportar<\/strong>.<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/kb.mailfence.com\/wp-content\/uploads\/2022\/03\/calendar-export.gif\" alt=\"exportar datos de Mailfence\" class=\"wp-image-2802\"\/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Consulta nuestra <a href=\"https:\/\/mailfence.com\/en\/doc\/calendar.jsp#import_export\">documentaci\u00f3n<\/a> para saber c\u00f3mo exportar varios o todos los eventos al mismo tiempo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"htoc-for-exporting-a-specific-contact\">Para <a href=\"https:\/\/blog.mailfence.com\/contact-management-software\/\">exportar un contacto concreto<\/a>:<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li id=\"htoc-haz-clic-con-el-bot-n-derecho-en-el-contacto-exportar-vcard\"><strong>Haz clic con el bot\u00f3n derecho<\/strong> en el contacto -> <strong>Exportar (vCard)<\/strong>.<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/kb.mailfence.com\/wp-content\/uploads\/2022\/03\/contact-export.gif\" alt=\"exportar datos de Mailfence\" class=\"wp-image-2803\"\/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\" id=\"htoc-for-exporting-your-openpgp-keypair-s-other-public-keys\">Para exportar tu(s) par(es) de claves OpenPGP\/otras claves p\u00fablicas:<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li id=\"htoc-consulta-este-art-culo\">Consulta <a href=\"https:\/\/kb.mailfence.com\/es\/kb\/como-exportar-pares-de-claves-openpgp-y-otras-claves-publicas\/\">este art\u00edculo<\/a>.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Puedes exportar datos desde la interfaz web de Mailfence de las dos formas siguientes: Crea una copia de seguridad: 1. Ajustes 2. Cuenta -&gt; Copia de seguridad: 3. Pulsa Exportar despu\u00e9s de elegir el elemento que quieras Exportar elementos seleccionados Para exportar un correo electr\u00f3nico concreto: Para exportar un documento&#8230;<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"footnotes":""},"ht-kb-category":[1205],"ht-kb-tag":[],"class_list":["post-9828","ht_kb","type-ht_kb","status-publish","format-standard","hentry","ht_kb_category-gestion-de-cuentas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00bfC\u00f3mo exporto datos de una cuenta Mailfence? - Mailfence Support<\/title>\n<meta name=\"description\" content=\"Hemos facilitado la exportaci\u00f3n de datos desde una cuenta Mailfence. Sigue estas instrucciones para aprender a exportar un correo electr\u00f3nico, documento, contacto o evento de calendario.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kb.mailfence.com\/es\/kb\/como-exporto-datos-de-una-cuenta-mailfence\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo exporto datos de una cuenta Mailfence? - Mailfence Support\" \/>\n<meta property=\"og:description\" content=\"Hemos facilitado la exportaci\u00f3n de datos desde una cuenta Mailfence. Sigue estas instrucciones para aprender a exportar un correo electr\u00f3nico, documento, contacto o evento de calendario.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kb.mailfence.com\/es\/kb\/como-exporto-datos-de-una-cuenta-mailfence\/\" \/>\n<meta property=\"og:site_name\" content=\"Mailfence Support\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mailfence\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-19T07:28:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kb.mailfence.com\/wp-content\/uploads\/2019\/12\/setting-8.png\" \/>\n\t<meta property=\"og:image:width\" content=\"199\" \/>\n\t<meta property=\"og:image:height\" content=\"310\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@mailfence\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"TechArticle\",\"@id\":\"https:\\\/\\\/kb.mailfence.com\\\/es\\\/kb\\\/como-exporto-datos-de-una-cuenta-mailfence\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kb.mailfence.com\\\/es\\\/kb\\\/como-exporto-datos-de-una-cuenta-mailfence\\\/\"},\"author\":{\"name\":\"Mailfence Support\",\"@id\":\"https:\\\/\\\/kb.mailfence.com\\\/es\\\/#\\\/schema\\\/person\\\/2ef2930e7a1ee7003aaeb419def643cd\"},\"headline\":\"\u00bfC\u00f3mo exporto datos de una cuenta Mailfence?\",\"datePublished\":\"2019-07-25T12:27:03+00:00\",\"dateModified\":\"2025-12-19T07:28:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kb.mailfence.com\\\/es\\\/kb\\\/como-exporto-datos-de-una-cuenta-mailfence\\\/\"},\"wordCount\":349,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/kb.mailfence.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kb.mailfence.com\\\/es\\\/kb\\\/como-exporto-datos-de-una-cuenta-mailfence\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kb.mailfence.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/setting-8.png\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/kb.mailfence.com\\\/es\\\/kb\\\/como-exporto-datos-de-una-cuenta-mailfence\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kb.mailfence.com\\\/es\\\/kb\\\/como-exporto-datos-de-una-cuenta-mailfence\\\/\",\"url\":\"https:\\\/\\\/kb.mailfence.com\\\/es\\\/kb\\\/como-exporto-datos-de-una-cuenta-mailfence\\\/\",\"name\":\"\u00bfC\u00f3mo exporto datos de una cuenta Mailfence? - Mailfence Support\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kb.mailfence.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kb.mailfence.com\\\/es\\\/kb\\\/como-exporto-datos-de-una-cuenta-mailfence\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kb.mailfence.com\\\/es\\\/kb\\\/como-exporto-datos-de-una-cuenta-mailfence\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kb.mailfence.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/setting-8.png\",\"datePublished\":\"2019-07-25T12:27:03+00:00\",\"dateModified\":\"2025-12-19T07:28:36+00:00\",\"description\":\"Hemos facilitado la exportaci\u00f3n de datos desde una cuenta Mailfence. Sigue estas instrucciones para aprender a exportar un correo electr\u00f3nico, documento, contacto o evento de calendario.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kb.mailfence.com\\\/es\\\/kb\\\/como-exporto-datos-de-una-cuenta-mailfence\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kb.mailfence.com\\\/es\\\/kb\\\/como-exporto-datos-de-una-cuenta-mailfence\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kb.mailfence.com\\\/es\\\/kb\\\/como-exporto-datos-de-una-cuenta-mailfence\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kb.mailfence.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/setting-8.png\",\"contentUrl\":\"https:\\\/\\\/kb.mailfence.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/setting-8.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kb.mailfence.com\\\/es\\\/kb\\\/como-exporto-datos-de-una-cuenta-mailfence\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/kb.mailfence.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gesti\u00f3n de cuentas\",\"item\":\"https:\\\/\\\/kb.mailfence.com\\\/es\\\/categoria-de-articulos\\\/gestion-de-cuentas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00bfC\u00f3mo exporto datos de una cuenta Mailfence?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kb.mailfence.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/kb.mailfence.com\\\/es\\\/\",\"name\":\"Mailfence Support\",\"description\":\"Secure and private email suite\",\"publisher\":{\"@id\":\"https:\\\/\\\/kb.mailfence.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kb.mailfence.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kb.mailfence.com\\\/es\\\/#organization\",\"name\":\"Mailfence\",\"url\":\"https:\\\/\\\/kb.mailfence.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kb.mailfence.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kb.mailfence.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/mailfence-logo-envelope-and-text.png\",\"contentUrl\":\"https:\\\/\\\/kb.mailfence.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/mailfence-logo-envelope-and-text.png\",\"width\":4961,\"height\":850,\"caption\":\"Mailfence\"},\"image\":{\"@id\":\"https:\\\/\\\/kb.mailfence.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mailfence\\\/\",\"https:\\\/\\\/x.com\\\/mailfence\",\"https:\\\/\\\/www.instagram.com\\\/mailfence_\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mailfence\",\"https:\\\/\\\/www.pinterest.com\\\/mailfence_com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@mailfence\",\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Mailfence\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kb.mailfence.com\\\/es\\\/#\\\/schema\\\/person\\\/2ef2930e7a1ee7003aaeb419def643cd\",\"name\":\"Mailfence Support\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/74ad1dfb6ee5a350f92123d2a8ce5cf95dbed666169690013c77801d2c837927?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/74ad1dfb6ee5a350f92123d2a8ce5cf95dbed666169690013c77801d2c837927?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/74ad1dfb6ee5a350f92123d2a8ce5cf95dbed666169690013c77801d2c837927?s=96&d=mm&r=g\",\"caption\":\"Mailfence Support\"},\"description\":\"End-to-end encrypted e-mail service that values and respects your privacy without compromising the ease-of-use. @mailfence @mailfence_fr\",\"sameAs\":[\"https:\\\/\\\/www.mailfence.com\",\"https:\\\/\\\/www.facebook.com\\\/mailfence\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mailfence\",\"https:\\\/\\\/x.com\\\/mailfence\",\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Mailfence\"],\"url\":\"https:\\\/\\\/kb.mailfence.com\\\/es\\\/author\\\/kbmfadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo exporto datos de una cuenta Mailfence? - Mailfence Support","description":"Hemos facilitado la exportaci\u00f3n de datos desde una cuenta Mailfence. Sigue estas instrucciones para aprender a exportar un correo electr\u00f3nico, documento, contacto o evento de calendario.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kb.mailfence.com\/es\/kb\/como-exporto-datos-de-una-cuenta-mailfence\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfC\u00f3mo exporto datos de una cuenta Mailfence? - Mailfence Support","og_description":"Hemos facilitado la exportaci\u00f3n de datos desde una cuenta Mailfence. Sigue estas instrucciones para aprender a exportar un correo electr\u00f3nico, documento, contacto o evento de calendario.","og_url":"https:\/\/kb.mailfence.com\/es\/kb\/como-exporto-datos-de-una-cuenta-mailfence\/","og_site_name":"Mailfence Support","article_publisher":"https:\/\/www.facebook.com\/mailfence\/","article_modified_time":"2025-12-19T07:28:36+00:00","og_image":[{"width":199,"height":310,"url":"https:\/\/kb.mailfence.com\/wp-content\/uploads\/2019\/12\/setting-8.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@mailfence","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"TechArticle","@id":"https:\/\/kb.mailfence.com\/es\/kb\/como-exporto-datos-de-una-cuenta-mailfence\/#article","isPartOf":{"@id":"https:\/\/kb.mailfence.com\/es\/kb\/como-exporto-datos-de-una-cuenta-mailfence\/"},"author":{"name":"Mailfence Support","@id":"https:\/\/kb.mailfence.com\/es\/#\/schema\/person\/2ef2930e7a1ee7003aaeb419def643cd"},"headline":"\u00bfC\u00f3mo exporto datos de una cuenta Mailfence?","datePublished":"2019-07-25T12:27:03+00:00","dateModified":"2025-12-19T07:28:36+00:00","mainEntityOfPage":{"@id":"https:\/\/kb.mailfence.com\/es\/kb\/como-exporto-datos-de-una-cuenta-mailfence\/"},"wordCount":349,"commentCount":0,"publisher":{"@id":"https:\/\/kb.mailfence.com\/es\/#organization"},"image":{"@id":"https:\/\/kb.mailfence.com\/es\/kb\/como-exporto-datos-de-una-cuenta-mailfence\/#primaryimage"},"thumbnailUrl":"https:\/\/kb.mailfence.com\/wp-content\/uploads\/2019\/12\/setting-8.png","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/kb.mailfence.com\/es\/kb\/como-exporto-datos-de-una-cuenta-mailfence\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/kb.mailfence.com\/es\/kb\/como-exporto-datos-de-una-cuenta-mailfence\/","url":"https:\/\/kb.mailfence.com\/es\/kb\/como-exporto-datos-de-una-cuenta-mailfence\/","name":"\u00bfC\u00f3mo exporto datos de una cuenta Mailfence? - Mailfence Support","isPartOf":{"@id":"https:\/\/kb.mailfence.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kb.mailfence.com\/es\/kb\/como-exporto-datos-de-una-cuenta-mailfence\/#primaryimage"},"image":{"@id":"https:\/\/kb.mailfence.com\/es\/kb\/como-exporto-datos-de-una-cuenta-mailfence\/#primaryimage"},"thumbnailUrl":"https:\/\/kb.mailfence.com\/wp-content\/uploads\/2019\/12\/setting-8.png","datePublished":"2019-07-25T12:27:03+00:00","dateModified":"2025-12-19T07:28:36+00:00","description":"Hemos facilitado la exportaci\u00f3n de datos desde una cuenta Mailfence. Sigue estas instrucciones para aprender a exportar un correo electr\u00f3nico, documento, contacto o evento de calendario.","breadcrumb":{"@id":"https:\/\/kb.mailfence.com\/es\/kb\/como-exporto-datos-de-una-cuenta-mailfence\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kb.mailfence.com\/es\/kb\/como-exporto-datos-de-una-cuenta-mailfence\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kb.mailfence.com\/es\/kb\/como-exporto-datos-de-una-cuenta-mailfence\/#primaryimage","url":"https:\/\/kb.mailfence.com\/wp-content\/uploads\/2019\/12\/setting-8.png","contentUrl":"https:\/\/kb.mailfence.com\/wp-content\/uploads\/2019\/12\/setting-8.png"},{"@type":"BreadcrumbList","@id":"https:\/\/kb.mailfence.com\/es\/kb\/como-exporto-datos-de-una-cuenta-mailfence\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/kb.mailfence.com\/es\/"},{"@type":"ListItem","position":2,"name":"Gesti\u00f3n de cuentas","item":"https:\/\/kb.mailfence.com\/es\/categoria-de-articulos\/gestion-de-cuentas\/"},{"@type":"ListItem","position":3,"name":"\u00bfC\u00f3mo exporto datos de una cuenta Mailfence?"}]},{"@type":"WebSite","@id":"https:\/\/kb.mailfence.com\/es\/#website","url":"https:\/\/kb.mailfence.com\/es\/","name":"Mailfence Support","description":"Secure and private email suite","publisher":{"@id":"https:\/\/kb.mailfence.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kb.mailfence.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kb.mailfence.com\/es\/#organization","name":"Mailfence","url":"https:\/\/kb.mailfence.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kb.mailfence.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/kb.mailfence.com\/wp-content\/uploads\/2022\/08\/mailfence-logo-envelope-and-text.png","contentUrl":"https:\/\/kb.mailfence.com\/wp-content\/uploads\/2022\/08\/mailfence-logo-envelope-and-text.png","width":4961,"height":850,"caption":"Mailfence"},"image":{"@id":"https:\/\/kb.mailfence.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mailfence\/","https:\/\/x.com\/mailfence","https:\/\/www.instagram.com\/mailfence_\/","https:\/\/www.linkedin.com\/company\/mailfence","https:\/\/www.pinterest.com\/mailfence_com\/","https:\/\/www.youtube.com\/@mailfence","https:\/\/en.wikipedia.org\/wiki\/Mailfence"]},{"@type":"Person","@id":"https:\/\/kb.mailfence.com\/es\/#\/schema\/person\/2ef2930e7a1ee7003aaeb419def643cd","name":"Mailfence Support","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/74ad1dfb6ee5a350f92123d2a8ce5cf95dbed666169690013c77801d2c837927?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/74ad1dfb6ee5a350f92123d2a8ce5cf95dbed666169690013c77801d2c837927?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/74ad1dfb6ee5a350f92123d2a8ce5cf95dbed666169690013c77801d2c837927?s=96&d=mm&r=g","caption":"Mailfence Support"},"description":"End-to-end encrypted e-mail service that values and respects your privacy without compromising the ease-of-use. @mailfence @mailfence_fr","sameAs":["https:\/\/www.mailfence.com","https:\/\/www.facebook.com\/mailfence","https:\/\/www.linkedin.com\/company\/mailfence","https:\/\/x.com\/mailfence","https:\/\/en.wikipedia.org\/wiki\/Mailfence"],"url":"https:\/\/kb.mailfence.com\/es\/author\/kbmfadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/kb.mailfence.com\/es\/wp-json\/wp\/v2\/ht-kb\/9828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kb.mailfence.com\/es\/wp-json\/wp\/v2\/ht-kb"}],"about":[{"href":"https:\/\/kb.mailfence.com\/es\/wp-json\/wp\/v2\/types\/ht_kb"}],"author":[{"embeddable":true,"href":"https:\/\/kb.mailfence.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kb.mailfence.com\/es\/wp-json\/wp\/v2\/comments?post=9828"}],"version-history":[{"count":4,"href":"https:\/\/kb.mailfence.com\/es\/wp-json\/wp\/v2\/ht-kb\/9828\/revisions"}],"predecessor-version":[{"id":12042,"href":"https:\/\/kb.mailfence.com\/es\/wp-json\/wp\/v2\/ht-kb\/9828\/revisions\/12042"}],"wp:attachment":[{"href":"https:\/\/kb.mailfence.com\/es\/wp-json\/wp\/v2\/media?parent=9828"}],"wp:term":[{"taxonomy":"ht_kb_category","embeddable":true,"href":"https:\/\/kb.mailfence.com\/es\/wp-json\/wp\/v2\/ht-kb-category?post=9828"},{"taxonomy":"ht_kb_tag","embeddable":true,"href":"https:\/\/kb.mailfence.com\/es\/wp-json\/wp\/v2\/ht-kb-tag?post=9828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}